{"id":114,"date":"2017-02-16T11:05:14","date_gmt":"2017-02-16T11:05:14","guid":{"rendered":"https:\/\/xml-io.proteusthemes.com\/medicpress\/?page_id=114"},"modified":"2025-02-21T20:03:08","modified_gmt":"2025-02-21T23:03:08","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/renatalutz.com.br\/index.php\/contact-us\/","title":{"rendered":"Contatos"},"content":{"rendered":"<div id=\"pl-114\"  class=\"panel-layout\" ><div id=\"pg-114-0\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-114-0-0\"  class=\"panel-grid-cell\" ><div id=\"panel-114-0-0-0\" class=\"so-panel widget widget_pw_person_profile widget-person-profile panel-first-child\" data-index=\"0\" >\n\t<div class=\"person-profile  h-card\">\n\t\t\t\t\t\t<div class=\"person-profile__container\">\n\t\t\t<div class=\"person-profile__basic-info\">\n\t\t\t\t\t\t\t\t\t<h4 class=\"person-profile__name  p-name\">\n\t\t\t\t\t\t\t\t\t\tPara agendar\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"person-profile__label\">\n\t\t\t\t\t\tWhatsapp\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"person-profile__icon-list  icon-list\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"icon-list__item  icon-list__item--featured\">\n\t\t\t\t\t\t\t<i class=\"fa  fa-laptop\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"icon-list__content\">\n\t\t\t\t\t\t\t\t<div class=\"icon-list__description\">\n\t\t\t\t\t\t\t\t\tRenata Lutz - Terapeuta\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"icon-list__text\">\n\t\t\t\t\t\t\t\t\t11 99919 0979\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n\n<\/div><div id=\"panel-114-0-0-1\" class=\"so-panel widget widget_pw_person_profile widget-person-profile panel-last-child\" data-index=\"1\" >\n\t<div class=\"person-profile  h-card\">\n\t\t\t\t\t\t<div class=\"person-profile__container\">\n\t\t\t<div class=\"person-profile__basic-info\">\n\t\t\t\t\t\t\t\t\t<h4 class=\"person-profile__name  p-name\">\n\t\t\t\t\t\t\t\t\t\tPara agendar\t\t\t\t\t\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"person-profile__label\">\n\t\t\t\t\t\tWhatsapp\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"person-profile__icon-list  icon-list\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"icon-list__item  icon-list__item--featured\">\n\t\t\t\t\t\t\t<i class=\"fa  fa-laptop\" aria-hidden=\"true\"><\/i>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"icon-list__content\">\n\t\t\t\t\t\t\t\t<div class=\"icon-list__description\">\n\t\t\t\t\t\t\t\t\tRenata Lutz - Terapeuta\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"icon-list__text\">\n\t\t\t\t\t\t\t\t\t11 99919 0979\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n\n<\/div><\/div><div id=\"pgc-114-0-1\"  class=\"panel-grid-cell panel-grid-cell-empty panel-grid-cell-mobile-last\" ><\/div><div id=\"pgc-114-0-2\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><\/div><div id=\"pg-114-1\"  class=\"panel-grid panel-no-style\" ><div id=\"pgc-114-1-0\"  class=\"panel-grid-cell\" ><div id=\"panel-114-1-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child\" data-index=\"2\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<h2 style=\"text-align: center;\">Envie a sua d\u00favida!<\/h2>\n<\/div>\n<\/div><\/div><div id=\"panel-114-1-0-1\" class=\"so-panel widget widget_sow-editor panel-last-child\" data-index=\"3\" ><div\n\t\t\t\n\t\t\tclass=\"so-widget-sow-editor so-widget-sow-editor-base\"\n\t\t\t\n\t\t>\n<div class=\"siteorigin-widget-tinymce textwidget\">\n\t<div role=\"form\" class=\"wpcf7\" id=\"wpcf7-f13-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\" role=\"alert\" aria-live=\"polite\"><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/114#wpcf7-f13-o1\" method=\"post\" class=\"wpcf7-form init\" novalidate=\"novalidate\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"13\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.2.2\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f13-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<div class=\"row\">\n<div class=\"col-xs-12  col-lg-4\">\n    <span class=\"wpcf7-form-control-wrap your-name\"><input type=\"text\" name=\"your-name\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome*\" \/><\/span>\n  <\/div>\n<div class=\"col-xs-12  col-lg-4\">\n    <span class=\"wpcf7-form-control-wrap your-number\"><input type=\"tel\" name=\"your-number\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-tel wpcf7-validates-as-tel form-control\" aria-invalid=\"false\" placeholder=\"Telefone\" \/><\/span>\n  <\/div>\n<div class=\"col-xs-12  col-lg-4\">\n    <span class=\"wpcf7-form-control-wrap your-email\"><input type=\"email\" name=\"your-email\" value=\"\" size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-required wpcf7-validates-as-email form-control\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail*\" \/><\/span>\n  <\/div>\n<div class=\"col-xs-12\">\n    <span class=\"wpcf7-form-control-wrap your-message\"><textarea name=\"your-message\" cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea form-control\" aria-invalid=\"false\" placeholder=\"Message\"><\/textarea><\/span><input type=\"submit\" value=\"Enviar\" class=\"wpcf7-form-control wpcf7-submit btn btn-secondary\" \/>\n  <\/div>\n<\/div>\n<div class=\"wpcf7-response-output\" role=\"alert\" aria-hidden=\"true\"><\/div><\/form><\/div>\n<\/div>\n<\/div><\/div><\/div><\/div><div id=\"pg-114-2\"  class=\"panel-grid panel-has-style\" ><div class=\"siteorigin-panels-stretch panel-row-style panel-row-style-for-114-2\" data-stretch-type=\"full-width-stretch\" ><div id=\"pgc-114-2-0\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><\/div><\/div><div id=\"pg-114-3\"  class=\"panel-grid panel-has-style\" ><div class=\"panel-row-style panel-row-style-for-114-3\" ><div id=\"pgc-114-3-0\"  class=\"panel-grid-cell panel-grid-cell-empty panel-grid-cell-mobile-last\" ><\/div><div id=\"pgc-114-3-1\"  class=\"panel-grid-cell panel-grid-cell-empty\" ><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Envie a sua d\u00favida!<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_joinchat":[],"footnotes":""},"class_list":{"0":"post-114","1":"page","2":"type-page","3":"status-publish","5":"clearfix","6":"article"},"acf":[],"_links":{"self":[{"href":"https:\/\/renatalutz.com.br\/index.php\/wp-json\/wp\/v2\/pages\/114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/renatalutz.com.br\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/renatalutz.com.br\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/renatalutz.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/renatalutz.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=114"}],"version-history":[{"count":16,"href":"https:\/\/renatalutz.com.br\/index.php\/wp-json\/wp\/v2\/pages\/114\/revisions"}],"predecessor-version":[{"id":1396,"href":"https:\/\/renatalutz.com.br\/index.php\/wp-json\/wp\/v2\/pages\/114\/revisions\/1396"}],"wp:attachment":[{"href":"https:\/\/renatalutz.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}